{"id":41,"count":4,"description":"","link":"https:\/\/mhhelpline.com\/en\/category\/psychologia-en\/","name":"Psychologia","slug":"psychologia-en","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archiwa Psychologia - Mental Health Helpline<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mhhelpline.com\/en\/category\/psychologia-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archiwa Psychologia - Mental Health Helpline\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mhhelpline.com\/en\/category\/psychologia-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Mental Health Helpline\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mhhelpline.com\/wp-content\/uploads\/2021\/06\/Logo@2x.png\" \/>\n\t<meta property=\"og:image:width\" content=\"696\" \/>\n\t<meta property=\"og:image:height\" content=\"417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/category\\\/psychologia-en\\\/\",\"url\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/category\\\/psychologia-en\\\/\",\"name\":\"Archiwa Psychologia - Mental Health Helpline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/category\\\/psychologia-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/category\\\/psychologia-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Psychologia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/\",\"name\":\"Mental Health Helpline\",\"description\":\"Pomoc psychologiczna on-line. Wspieramy w kryzysie, niesiemy pomoc.\",\"publisher\":{\"@id\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/#organization\"},\"alternateName\":\"MHHL\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/#organization\",\"name\":\"Mental Health HelpLine\",\"alternateName\":\"MHHL\",\"url\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mhhelpline.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo.png\",\"contentUrl\":\"https:\\\/\\\/mhhelpline.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo.png\",\"width\":348,\"height\":209,\"caption\":\"Mental Health HelpLine\"},\"image\":{\"@id\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mentalhealthhelplinepl\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mental-health-help-line\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archiwa Psychologia - Mental Health Helpline","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mhhelpline.com\/en\/category\/psychologia-en\/","og_locale":"en_US","og_type":"article","og_title":"Archiwa Psychologia - Mental Health Helpline","og_url":"https:\/\/mhhelpline.com\/en\/category\/psychologia-en\/","og_site_name":"Mental Health Helpline","og_image":[{"width":696,"height":417,"url":"https:\/\/mhhelpline.com\/wp-content\/uploads\/2021\/06\/Logo@2x.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mhhelpline.com\/en\/category\/psychologia-en\/","url":"https:\/\/mhhelpline.com\/en\/category\/psychologia-en\/","name":"Archiwa Psychologia - Mental Health Helpline","isPartOf":{"@id":"https:\/\/mhhelpline.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/mhhelpline.com\/en\/category\/psychologia-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/mhhelpline.com\/en\/category\/psychologia-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/mhhelpline.com\/en\/"},{"@type":"ListItem","position":2,"name":"Psychologia"}]},{"@type":"WebSite","@id":"https:\/\/mhhelpline.com\/en\/#website","url":"https:\/\/mhhelpline.com\/en\/","name":"Mental Health Helpline","description":"Pomoc psychologiczna on-line. Wspieramy w kryzysie, niesiemy pomoc.","publisher":{"@id":"https:\/\/mhhelpline.com\/en\/#organization"},"alternateName":"MHHL","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mhhelpline.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mhhelpline.com\/en\/#organization","name":"Mental Health HelpLine","alternateName":"MHHL","url":"https:\/\/mhhelpline.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mhhelpline.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mhhelpline.com\/wp-content\/uploads\/2021\/06\/Logo.png","contentUrl":"https:\/\/mhhelpline.com\/wp-content\/uploads\/2021\/06\/Logo.png","width":348,"height":209,"caption":"Mental Health HelpLine"},"image":{"@id":"https:\/\/mhhelpline.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mentalhealthhelplinepl","https:\/\/www.linkedin.com\/company\/mental-health-help-line\/"]}]}},"_links":{"self":[{"href":"https:\/\/mhhelpline.com\/en\/wp-json\/wp\/v2\/categories\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mhhelpline.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/mhhelpline.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/mhhelpline.com\/en\/wp-json\/wp\/v2\/posts?categories=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}