{"id":4,"name":"Maciej Dukata","url":"","description":"","link":"https:\/\/mhhelpline.com\/en\/author\/maciek\/","slug":"maciek","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/a1b733ba401deae5a00807d5533c42746b83ee8db38852a62298437508f381e0?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/a1b733ba401deae5a00807d5533c42746b83ee8db38852a62298437508f381e0?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/a1b733ba401deae5a00807d5533c42746b83ee8db38852a62298437508f381e0?s=96&d=mm&r=g"},"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Maciej Dukata, Autor w serwisie Mental Health Helpline<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mhhelpline.com\/en\/author\/maciek\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Maciej Dukata, Autor w serwisie Mental Health Helpline\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mhhelpline.com\/author\/maciek\/\" \/>\n<meta property=\"og:site_name\" content=\"Mental Health Helpline\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/1283fc99fdba1e6ae61ad86fc0465dbf?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/mhhelpline.com\\\/author\\\/maciek\\\/\",\"url\":\"https:\\\/\\\/mhhelpline.com\\\/author\\\/maciek\\\/\",\"name\":\"Maciej Dukata, Autor w serwisie Mental Health Helpline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mhhelpline.com\\\/author\\\/maciek\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mhhelpline.com\\\/author\\\/maciek\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mhhelpline.com\\\/author\\\/maciek\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archiwum dla Maciej Dukata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/\",\"name\":\"Mental Health Helpline\",\"description\":\"Pomoc psychologiczna on-line. Wspieramy w kryzysie, niesiemy pomoc.\",\"publisher\":{\"@id\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/#organization\"},\"alternateName\":\"MHHL\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/#organization\",\"name\":\"Mental Health HelpLine\",\"alternateName\":\"MHHL\",\"url\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mhhelpline.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo.png\",\"contentUrl\":\"https:\\\/\\\/mhhelpline.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/Logo.png\",\"width\":348,\"height\":209,\"caption\":\"Mental Health HelpLine\"},\"image\":{\"@id\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mentalhealthhelplinepl\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/mental-health-help-line\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mhhelpline.com\\\/en\\\/#\\\/schema\\\/person\\\/7b90a598788b6a871accc5fe4cf3c05c\",\"name\":\"Maciej Dukata\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1b733ba401deae5a00807d5533c42746b83ee8db38852a62298437508f381e0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1b733ba401deae5a00807d5533c42746b83ee8db38852a62298437508f381e0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a1b733ba401deae5a00807d5533c42746b83ee8db38852a62298437508f381e0?s=96&d=mm&r=g\",\"caption\":\"Maciej Dukata\"},\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mhhelpline.com\\\/author\\\/maciek\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maciej Dukata, Autor w serwisie Mental Health Helpline","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mhhelpline.com\/en\/author\/maciek\/","og_locale":"en_US","og_type":"profile","og_title":"Maciej Dukata, Autor w serwisie Mental Health Helpline","og_url":"https:\/\/mhhelpline.com\/author\/maciek\/","og_site_name":"Mental Health Helpline","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/1283fc99fdba1e6ae61ad86fc0465dbf?s=500&d=mm&r=g","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/mhhelpline.com\/author\/maciek\/","url":"https:\/\/mhhelpline.com\/author\/maciek\/","name":"Maciej Dukata, Autor w serwisie Mental Health Helpline","isPartOf":{"@id":"https:\/\/mhhelpline.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/mhhelpline.com\/author\/maciek\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mhhelpline.com\/author\/maciek\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mhhelpline.com\/author\/maciek\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/mhhelpline.com\/en\/"},{"@type":"ListItem","position":2,"name":"Archiwum dla Maciej Dukata"}]},{"@type":"WebSite","@id":"https:\/\/mhhelpline.com\/en\/#website","url":"https:\/\/mhhelpline.com\/en\/","name":"Mental Health Helpline","description":"Pomoc psychologiczna on-line. Wspieramy w kryzysie, niesiemy pomoc.","publisher":{"@id":"https:\/\/mhhelpline.com\/en\/#organization"},"alternateName":"MHHL","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mhhelpline.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mhhelpline.com\/en\/#organization","name":"Mental Health HelpLine","alternateName":"MHHL","url":"https:\/\/mhhelpline.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mhhelpline.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/mhhelpline.com\/wp-content\/uploads\/2021\/06\/Logo.png","contentUrl":"https:\/\/mhhelpline.com\/wp-content\/uploads\/2021\/06\/Logo.png","width":348,"height":209,"caption":"Mental Health HelpLine"},"image":{"@id":"https:\/\/mhhelpline.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mentalhealthhelplinepl","https:\/\/www.linkedin.com\/company\/mental-health-help-line\/"]},{"@type":"Person","@id":"https:\/\/mhhelpline.com\/en\/#\/schema\/person\/7b90a598788b6a871accc5fe4cf3c05c","name":"Maciej Dukata","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/a1b733ba401deae5a00807d5533c42746b83ee8db38852a62298437508f381e0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a1b733ba401deae5a00807d5533c42746b83ee8db38852a62298437508f381e0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a1b733ba401deae5a00807d5533c42746b83ee8db38852a62298437508f381e0?s=96&d=mm&r=g","caption":"Maciej Dukata"},"mainEntityOfPage":{"@id":"https:\/\/mhhelpline.com\/author\/maciek\/"}}]}},"_links":{"self":[{"href":"https:\/\/mhhelpline.com\/en\/wp-json\/wp\/v2\/users\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mhhelpline.com\/en\/wp-json\/wp\/v2\/users"}]}}